{"id":260,"date":"2025-03-09T19:54:59","date_gmt":"2025-03-09T18:54:59","guid":{"rendered":"https:\/\/www.loris-kitchen.de\/?p=260"},"modified":"2025-03-23T20:59:41","modified_gmt":"2025-03-23T19:59:41","slug":"original-sticky-toffee-pudding","status":"publish","type":"post","link":"https:\/\/www.loris-kitchen.de\/index.php\/2025\/03\/09\/original-sticky-toffee-pudding\/","title":{"rendered":"Original Sticky Toffee Pudding"},"content":{"rendered":"\n<p><strong>Zutaten:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>180 g entkernte Datteln, grob gehackt (oder Dattelpaste vom DM)<\/li>\n\n\n\n<li>300 ml kochendes Wasser<\/li>\n\n\n\n<li>1 TL Natron<\/li>\n\n\n\n<li>60 g Butter<\/li>\n\n\n\n<li>180 g wei\u00dfer Zucker<\/li>\n\n\n\n<li>240 g Mehl<\/li>\n\n\n\n<li>1 TL Backpulver<\/li>\n\n\n\n<li>1 Ei<\/li>\n\n\n\n<li>1 TL Vanilleextrakt<\/li>\n<\/ul>\n\n\n\n<p><strong>F\u00fcr die Karamellsauce:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>60 g Butter<\/li>\n\n\n\n<li>90 g brauner Zucker<\/li>\n\n\n\n<li>100 ml Sahne<\/li>\n\n\n\n<li>1\/2 TL Meersalzflocken<\/li>\n<\/ul>\n\n\n\n<p><strong>Zubereitung:<\/strong><\/p>\n\n\n\n<p>Backofen auf 160 Grad Ober Unterhitze vorheizen. <\/p>\n\n\n\n<p>Datteln in eine Sch\u00fcssel geben, mit dem Natron mischen und kochendes Wasser dar\u00fcbergie\u00dfen. Stehen lassen. In der Zwischenzeit Butter und Zucker schaumig r\u00fchren, bis blasse Farbe entsteht. (ich pers\u00f6nlich finde es geht am einfachsten in der K\u00fcchenmaschine). Nach und nach Ei, Mehl und Backpulver dazugeben. Dann Datteln mit der Fl\u00fcssigkeit dazugeben, zum Schluss die Vanilleessenz. Alles gut miteinander vermischen. Teig in eine gefettete Auflaufform (oder individuelle kleine F\u00f6rmchen) f\u00fcllen und im Backofen ca. 35 Minuten backen. (Man kann die Probe machen wie gew\u00f6hnlich beim Backen, mit Holzstab, sollte nichts mehr dran kleben bleiben, ist der Pudding fertig)<\/p>\n\n\n\n<p>F\u00fcr die So\u00dfe alle Zutaten zusammen in einem Topf zum Kochen bringen, unter R\u00fchren 2 Minuten kochen lassen und \u00fcber den warmen Pudding gie\u00dfen. Ergibt ca. 4-6 Portionen, je nach Appetit.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Dig in!<\/h2>\n\n\n\n<p class=\"has-small-font-size\">Rezept von Chefkoch<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"1000\" data-id=\"366\" src=\"https:\/\/www.loris-kitchen.de\/wp-content\/uploads\/2025\/03\/20250323_185338-kl.jpg\" alt=\"\" class=\"wp-image-366\" srcset=\"https:\/\/www.loris-kitchen.de\/wp-content\/uploads\/2025\/03\/20250323_185338-kl.jpg 750w, https:\/\/www.loris-kitchen.de\/wp-content\/uploads\/2025\/03\/20250323_185338-kl-225x300.jpg 225w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"364\" src=\"https:\/\/www.loris-kitchen.de\/wp-content\/uploads\/2025\/03\/20250323_181254-768x1024.jpg\" alt=\"\" class=\"wp-image-364\" srcset=\"https:\/\/www.loris-kitchen.de\/wp-content\/uploads\/2025\/03\/20250323_181254-768x1024.jpg 768w, https:\/\/www.loris-kitchen.de\/wp-content\/uploads\/2025\/03\/20250323_181254-225x300.jpg 225w, https:\/\/www.loris-kitchen.de\/wp-content\/uploads\/2025\/03\/20250323_181254-1152x1536.jpg 1152w, https:\/\/www.loris-kitchen.de\/wp-content\/uploads\/2025\/03\/20250323_181254-1536x2048.jpg 1536w, https:\/\/www.loris-kitchen.de\/wp-content\/uploads\/2025\/03\/20250323_181254-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Zutaten: F\u00fcr die Karamellsauce: Zubereitung: Backofen auf 160 Grad Ober Unterhitze vorheizen. Datteln in eine Sch\u00fcssel geben, mit dem Natron mischen und kochendes Wasser dar\u00fcbergie\u00dfen. &hellip; <\/p>\n","protected":false},"author":1,"featured_media":365,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,19,15,4,3],"tags":[],"class_list":["post-260","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-desserts","category-england","category-laender","category-rezepte"],"_links":{"self":[{"href":"https:\/\/www.loris-kitchen.de\/index.php\/wp-json\/wp\/v2\/posts\/260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.loris-kitchen.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.loris-kitchen.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.loris-kitchen.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.loris-kitchen.de\/index.php\/wp-json\/wp\/v2\/comments?post=260"}],"version-history":[{"count":4,"href":"https:\/\/www.loris-kitchen.de\/index.php\/wp-json\/wp\/v2\/posts\/260\/revisions"}],"predecessor-version":[{"id":370,"href":"https:\/\/www.loris-kitchen.de\/index.php\/wp-json\/wp\/v2\/posts\/260\/revisions\/370"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.loris-kitchen.de\/index.php\/wp-json\/wp\/v2\/media\/365"}],"wp:attachment":[{"href":"https:\/\/www.loris-kitchen.de\/index.php\/wp-json\/wp\/v2\/media?parent=260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.loris-kitchen.de\/index.php\/wp-json\/wp\/v2\/categories?post=260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.loris-kitchen.de\/index.php\/wp-json\/wp\/v2\/tags?post=260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}